{"id":1846,"date":"2014-08-08T16:38:53","date_gmt":"2014-08-08T16:38:53","guid":{"rendered":"http:\/\/cocolingua.com\/en\/?p=1846"},"modified":"2024-03-14T20:33:38","modified_gmt":"2024-03-14T20:33:38","slug":"comparte-con-nosotros-estamos-en-agosto-la-mitad-del-verano","status":"publish","type":"post","link":"https:\/\/cocolingua.com\/es\/comparte-con-nosotros-estamos-en-agosto-la-mitad-del-verano\/","title":{"rendered":"Comparte con Nosotros &#8211;  Estamos en Agosto, la mitad del verano\u2026"},"content":{"rendered":"<p><b>Con el calor\u00f3n que hace en el d\u00eda, piensa en las siguientes cosas que podr\u00edas hacer: <\/b><\/p>\n<ol>\n<li>1. Tumbarte en la playa como una lagartija.<\/li>\n<li>2. Hacer un curso de espa\u00f1ol de verano.<\/li>\n<li>3. Intentar de no volverse loco y ver las \u00faltimas pel\u00edculas del 2014.<\/li>\n<li>4. Descubrir y disfrutar de Lanzarote.<\/li>\n<\/ol>\n<p>\u00bfCu\u00e1l escoger\u00edas t\u00fa? \u00bfCu\u00e1l es tu opini\u00f3n? \u00a1D\u00ednoslo ahora para compartir con los dem\u00e1s!<!--more--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el calor\u00f3n que hace en el d\u00eda, piensa en las siguientes cosas que podr\u00edas hacer: 1. Tumbarte en la playa como una lagartija. 2. Hacer un curso de espa\u00f1ol de verano. 3. Intentar de no volverse loco y ver las \u00faltimas pel\u00edculas del 2014. 4. Descubrir y disfrutar de Lanzarote. \u00bfCu\u00e1l escoger\u00edas t\u00fa? \u00bfCu\u00e1l  [&#8230;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1846","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/posts\/1846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/comments?post=1846"}],"version-history":[{"count":1,"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/posts\/1846\/revisions"}],"predecessor-version":[{"id":14062,"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/posts\/1846\/revisions\/14062"}],"wp:attachment":[{"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/media?parent=1846"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/categories?post=1846"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocolingua.com\/es\/wp-json\/wp\/v2\/tags?post=1846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}