{"id":14015,"date":"2014-02-07T16:54:09","date_gmt":"2014-02-07T16:54:09","guid":{"rendered":"https:\/\/cocolingua.com\/eine-reise-nach-bolivien-von-odaly-fernandez-freitag-den-21-februar-um-1800-uhr\/"},"modified":"2014-02-07T16:54:09","modified_gmt":"2014-02-07T16:54:09","slug":"eine-reise-nach-bolivien-von-odaly-fernandez-freitag-den-21-februar-um-1800-uhr","status":"publish","type":"post","link":"https:\/\/cocolingua.com\/de\/eine-reise-nach-bolivien-von-odaly-fernandez-freitag-den-21-februar-um-1800-uhr\/","title":{"rendered":"Eine Reise nach Bolivien \u2013 von Odaly Fern\u00e1ndez \u2013 Freitag, den 21. Februar um 18:00 Uhr"},"content":{"rendered":"<p><span>Ein Einblick in die Vielfalt dieses wundervollen Landes. Ein Bericht einer Bolivianerin, die jetzt mit ihrer Familie auf Lanzarote lebt. Sie wird uns durch ein Land mit verschiedenen Klimata und Kulturen f\u00fchren, wo die offizielle Sprache Spanisch ist, die jedoch nur von etwa 70% der Bev\u00f6lkerung gesprochen wird&#8230;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ein Einblick in die Vielfalt dieses wundervollen Landes. Ein Bericht einer Bolivianerin, die jetzt mit ihrer Familie auf Lanzarote lebt. Sie wird uns durch ein Land mit verschiedenen Klimata und Kulturen f\u00fchren, wo die offizielle Sprache Spanisch ist, die jedoch nur von etwa 70% der Bev\u00f6lkerung gesprochen wird&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1336,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[74,2],"tags":[],"class_list":["post-14015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten","category-noticias"],"_links":{"self":[{"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/posts\/14015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/comments?post=14015"}],"version-history":[{"count":0,"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/posts\/14015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/media\/1336"}],"wp:attachment":[{"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/media?parent=14015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/categories?post=14015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cocolingua.com\/de\/wp-json\/wp\/v2\/tags?post=14015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}